{"id":245,"date":"2024-12-11T12:00:29","date_gmt":"2024-12-11T06:30:29","guid":{"rendered":"https:\/\/cset.ac.in\/student-corner\/?page_id=245"},"modified":"2024-12-11T12:00:29","modified_gmt":"2024-12-11T06:30:29","slug":"games-sports-club","status":"publish","type":"page","link":"https:\/\/cset.ac.in\/student-corner\/games-sports-club\/","title":{"rendered":"Games &amp; Sports Club"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>Games &amp; Sports Club<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Games &amp; Sports Club<\/p>\n","protected":false},"author":55,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"left-sidebar","site-content-layout":"","ast-site-content-layout":"","site-content-style":"boxed","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-245","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cset.ac.in\/student-corner\/wp-json\/wp\/v2\/pages\/245"}],"collection":[{"href":"https:\/\/cset.ac.in\/student-corner\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cset.ac.in\/student-corner\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cset.ac.in\/student-corner\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/cset.ac.in\/student-corner\/wp-json\/wp\/v2\/comments?post=245"}],"version-history":[{"count":1,"href":"https:\/\/cset.ac.in\/student-corner\/wp-json\/wp\/v2\/pages\/245\/revisions"}],"predecessor-version":[{"id":246,"href":"https:\/\/cset.ac.in\/student-corner\/wp-json\/wp\/v2\/pages\/245\/revisions\/246"}],"wp:attachment":[{"href":"https:\/\/cset.ac.in\/student-corner\/wp-json\/wp\/v2\/media?parent=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}